{"id":263,"date":"2012-12-07T20:59:18","date_gmt":"2012-12-07T18:59:18","guid":{"rendered":"http:\/\/umparkour.com\/web\/?p=263"},"modified":"2013-11-13T16:31:06","modified_gmt":"2013-11-13T15:31:06","slug":"objetivos","status":"publish","type":"post","link":"http:\/\/umparkour.com\/web\/objetivos\/","title":{"rendered":"Objetivos"},"content":{"rendered":"<p>Nadie entrena en vano. Nadie sale a la calle, o a al gimnasio, o coge la bici, o realiza cualquier actividad por el mero hecho de hacerla. Ese es un camino que llevar\u00eda al abandono de la actividad y por lo tanto, al fracaso en la misma.<\/p>\n<p>Con el Parkour pasa lo mismo, nadie sale a entrenar solo por entrenar. Por pegar unos saltos o subir algunos muros. El hacerlo ser\u00eda poner fecha de caducidad al entrenamiento, es por eso que cada traceur busca algunos objetivos que le ayuden a continuar y seguir adelante con su entrenamiento y adem\u00e1s enfocarlo en una u otra direcci\u00f3n.<\/p>\n<p>En muchas entrevistas o reportajes se ha escrito o dicho que el objetivo es saltar cada vez m\u00e1s largo y m\u00e1s alto, conseguir as\u00ed ir superando marcas personales como si de records de atletismo se tratase. \u00bfPero es eso posible? S\u00ed durante un tiempo, pero si tu misi\u00f3n final es que tu Parkour sea una carrera de larga distancia llegar\u00e1 un momento en el que ese objetivo deba ceder a otros m\u00e1s realistas y acordes a tu capacidad en esa \u00e9poca.<\/p>\n<p>De esa forma se deben ir variando los objetivos en el entrenamiento dependiendo de cu\u00e1l sea nuestra situaci\u00f3n actual. Hay que adaptarse y si bien el buscar ir un paso m\u00e1s all\u00e1 siempre es positivo, se debe conocer cu\u00e1l debe ser ese paso: \u00bfLongitud? \u00bfAltura? \u00bfControl? \u00bfT\u00e9cnica? \u00bfForma f\u00edsica? \u00bfConstancia en el entrenamiento? \u00bfSentirse bien?&#8230;<\/p>\n<p>A mi parecer debe existir un objetivo que est\u00e9 siempre por encima de cualquier otro: Conocernos. Conocer la capacidad de nuestro cuerpo, saber hasta d\u00f3nde exigirle y c\u00f3mo conseguir mejorarlo. Conocer nuestra mentalidad y conocer c\u00f3mo hacerla m\u00e1s fuerte y que eso nos ayude en el entrenamiento.<\/p>\n<p>Mucha gente entrena queriendo saltar m\u00e1s largo y desde m\u00e1s alto, queriendo ser fuertes de verdad o buscando una velocidad cada vez m\u00e1s r\u00e1pida en el desplazamiento por ejemplo, pero se despreocupan de conocer c\u00f3mo llevar a su cuerpo a conseguir esos objetivos. Es por eso que conocernos debe ser prioritario y nunca olvidado en nuestro entrenamiento. Saber qu\u00e9 podemos y no podemos hacer y c\u00f3mo conseguir hacerlo, c\u00f3mo llevar a nuestro cuerpo y nuestra mente a superarse cada d\u00eda empieza por conocernos a nosotros mismos y entender y aceptar objetivos reales que algunos se mantendr\u00e1n en el tiempo y otros simplemente deber\u00e1n ir variando nuestros m\u00e9todos de entrenamiento.<\/p>\n<p><strong>Si el objetivo final es durar; <em>conocer, respetar y saber hacer funcionar nuestro cuerpo y mente debe ser primordial<\/em><\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211;<br \/>\n<span style=\"color: #888888;\">Art\u00edculo original escrito por Dani Sampayo para <a href=\"http:\/\/www.umparkour.com\" target=\"_blank\"><span style=\"color: #888888;\">www.umparkour.com<\/span><\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"Objetivos\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>Nadie entrena en vano. Nadie sale a la calle, o a al gimnasio, o coge la bici, o realiza cualquier actividad por el mero hecho de hacerla. Ese es un camino que llevar\u00eda al abandono de la actividad y por lo tanto, al fracaso en la misma. Con el Parkour pasa lo mismo, nadie sale [&hellip;]<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"Objetivos\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":585,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[29,17,16,30,203],"class_list":["post-263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-general","tag-articulos-2","tag-dani-sampayo","tag-entrenamiento","tag-general-2","tag-objetivos"],"_links":{"self":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":3,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/263\/revisions"}],"predecessor-version":[{"id":844,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/263\/revisions\/844"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media\/585"}],"wp:attachment":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media?parent=263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/categories?post=263"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/tags?post=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}