{"id":206,"date":"2012-04-14T17:36:51","date_gmt":"2012-04-14T15:36:51","guid":{"rendered":"http:\/\/umparkour.com\/web\/?p=206"},"modified":"2013-11-13T11:02:44","modified_gmt":"2013-11-13T10:02:44","slug":"sarcelles","status":"publish","type":"post","link":"http:\/\/umparkour.com\/web\/sarcelles\/","title":{"rendered":"Sarcelles"},"content":{"rendered":"<p>\u00bfQu\u00e9 importancia se le da al entrenamiento f\u00edsico?. Mucha de la gente que comienza tiene la imagen de un Parkour que es solo movimiento, divertirse y salir a saltar con los amigos. Pero detr\u00e1s de eso debe existir un entrenamiento f\u00edsico y t\u00e9cnico que ayude a avanzar y a mejorar la calidad de los entrenamientos y por ende, del Parkour que se practique.<\/p>\n<p>Es por eso que hoy os comparto un v\u00eddeo (de <a href=\"http:\/\/www.youtube.com\/user\/slamcamspam\/videos\" target=\"_blank\">Julie Angel<\/a>) que ense\u00f1a todas estas cualidades, un entrenamiento f\u00edsico y t\u00e9cnico en el m\u00edtico bosque de Sarcelles por parte de <a href=\"http:\/\/www.majesticforce.com\/\" target=\"_blank\">Majestic Force<\/a> (Yamakasi) y <a href=\"http:\/\/www.parkourgenerations.com\/\" target=\"_blank\">Parkour Generations<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><object width=\"480\" height=\"360\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/Rwx7BOsb2FM?version=3&amp;hl=es_ES\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed width=\"480\" height=\"360\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/Rwx7BOsb2FM?version=3&amp;hl=es_ES\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"Sarcelles\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 importancia se le da al entrenamiento f\u00edsico?. Mucha de la gente que comienza tiene la imagen de un Parkour que es solo movimiento, divertirse y salir a saltar con los amigos. Pero detr\u00e1s de eso debe existir un entrenamiento f\u00edsico y t\u00e9cnico que ayude a avanzar y a mejorar la calidad de los entrenamientos [&hellip;]<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"Sarcelles\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,274],"tags":[170,161,46,169,162,13],"class_list":["post-206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-multimedia","category-reportajes","tag-julie-angel","tag-multimedia-2","tag-parkour-generations","tag-sarcelles","tag-video","tag-yamakasi"],"_links":{"self":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":2,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/206\/revisions"}],"predecessor-version":[{"id":661,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/206\/revisions\/661"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media\/660"}],"wp:attachment":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media?parent=206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/categories?post=206"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/tags?post=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}