{"id":1083,"date":"2014-06-09T14:38:40","date_gmt":"2014-06-09T13:38:40","guid":{"rendered":"http:\/\/umparkour.com\/web\/?p=1083"},"modified":"2014-06-09T14:38:40","modified_gmt":"2014-06-09T13:38:40","slug":"la-guerra-entrenamiento-fuerza-de-voluntad-y-el-eterno-oponente","status":"publish","type":"post","link":"http:\/\/umparkour.com\/web\/la-guerra-entrenamiento-fuerza-de-voluntad-y-el-eterno-oponente\/","title":{"rendered":"La Guerra: Entrenamiento, Fuerza de Voluntad y el Eterno Oponente"},"content":{"rendered":"<p>No est\u00e1 de moda en estos d\u00edas el hablar del entrenamiento o la auto-mejora en t\u00e9rminos de conflicto \u2013 a menudo escuchamos que se supone que hay que entrenar inteligente, no duro; a nuestro ritmo; para trabajar dentro de nuestros l\u00edmites; para adherirnos a los principios de la ciencia deportiva de cabo a rabo. Y, desde un punto de vista fisiol\u00f3gico, esto es a menudo un consejo sensato y ser\u00eda sabio seguirlo.<\/p>\n<p>Sin embargo en la pr\u00e1ctica del parkour tambi\u00e9n hay una guerra libr\u00e1ndose: una batalla psicol\u00f3gica que se nos presenta en cada momento que damos un paso m\u00e1s en un salto o movimiento que no dominamos, cada vez que el miedo al fallo o a la ca\u00edda fija sobre nosotros su oscura mirada y nos dice que nos demos por vencidos, que nos vayamos a casa, que lo intentemos otro d\u00eda, como excus\u00e1ndonos a nosotros mismos para que aceptemos la derrota.<\/p>\n<p>Este oponente es, por supuesto, nuestro propio yo, manifest\u00e1ndose a trav\u00e9s del desaf\u00edo del terreno que encontramos en nuestro entrenamiento. Y este adversario, simplemente, no puede ser batido jugando de forma inteligente, o trabajando dentro de nuestros l\u00edmites. Tiene que ser encarado de frente, confrontado en un sentido primario y luchando hasta que \u00e9l, o t\u00fa, sea sometido.<\/p>\n<p>Aqu\u00ed es donde necesitamos algo de ese \u201cmachaque\u201d pasado de moda. Esta es tambi\u00e9n la parte de nuestro entrenamiento que no se gestiona f\u00e1cilmente. Convertirse en alguien fuerte, o en alguien en forma, o r\u00e1pido, o aprender a moverse bien, no es un proceso complicado: aplica regularmente el entrenamiento correcto por el tiempo suficiente y ver\u00e1s los resultados. Es simple.<\/p>\n<p>En lo que concierne a la mente, sin embargo, es cualquier cosa menos (simple)&#8230;<\/p>\n<p><a href=\"http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1084\" src=\"http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1.jpg\" alt=\"WAR1\" width=\"600\" height=\"600\" srcset=\"http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1.jpg 600w, http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1-150x150.jpg 150w, http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1-300x300.jpg 300w, http:\/\/umparkour.com\/web\/wp-content\/uploads\/2014\/06\/WAR1-50x50.jpg 50w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Es imposible predecir c\u00f3mo alguien va a reaccionar al desaf\u00edo de su mismo ser en esta situaci\u00f3n \u2013 \u00bfse acobardar\u00e1 por el miedo, o se crecer\u00e1 para superarse? \u00bfDemostrar\u00e1n ellos su fuerza interior requerida para empujarse a s\u00ed mismo sobre estos retos, o buscar\u00e1 un camino m\u00e1s f\u00e1cil? La cruda realidad es que hasta que no estemos enfrentados a la batalla no tenemos ni idea de c\u00f3mo reaccionaremos. Tampoco nadie podr\u00e1 ser capaz de augurar de manera infalible c\u00f3mo le ir\u00e1 a nadie m\u00e1s en este tipo de situaciones: muchas veces hemos visto profesionales destacando durante aspectos \u201cseguros\u201d del entrenamiento, probablemente en una clase en interior, s\u00f3lo para rehusarse cuando encaran los mismos movimientos en un entorno en el que perciben m\u00e1s de \u201calto-riesgo\u201d<\/p>\n<p>La mente es la m\u00e1s escurridiza de los adversarios, y la m\u00e1s astuta, y la m\u00e1s persistente. Y usar\u00e1 todos los trucos a su alcance para animarte a abandonar la lucha. \u201cHoy est\u00e1s cansado\u201d, susurrar\u00e1. O quiz\u00e1s, \u201cest\u00e1 un poco h\u00famedo a\u00fan por la lluvia, mejor dejarlo para otro d\u00eda\u201d. \u201cNo te exijas demasiado, podr\u00edas hacerte da\u00f1o\u201d, advertir\u00e1. Y finalmente, te calmar\u00e1, \u201csiempre podr\u00e1s volver ma\u00f1ana y hacerlo. Acaba por hoy\u201d. Pero escucha esta voz sibilina todo el tiempo, y pronto se extinguir\u00e1 el fuego dentro de ti por completo: y un d\u00eda cuando realmente quieras hacer un salto, te dar\u00e1s cuenta que simplemente no puedes reunir la fuerza.<\/p>\n<p>\u00bfC\u00f3mo prevenir esto? No escuchando esa voz \u2014o al menos no muy a menudo. Tienes que combatir esta batalla interna y ganar m\u00e1s a menudo que perder. As\u00ed que escucha lo que la voz tiene que decir (\u00a1qui\u00e9n sabe, una o dos veces, en realidad podr\u00eda hablar con sentido!), Presta atenci\u00f3n a sus avisos y a sus consejos \u2014entonces toma nota y arch\u00edvalos en la carpeta de \u00abconsiderados\u00bb, dile que cierre la maldita boca y vuelve a superar cualquier obst\u00e1culo que se encuentre en tu camino.<\/p>\n<p>Hay una mir\u00edada de diferentes m\u00e9todos para luchar esta guerra \u2014No quiero decir \u201cganar\u201d porque no es una guerra que pueda ganarse siempre, en absoluto \u2014 y he visto a personas que emplean con \u00e9xito diferentes estrategias: t\u00e9cnicas de visualizaci\u00f3n, t\u00e9cnicas de distracci\u00f3n, rabia, mantras, m\u00fasica\u2026 pero en alg\u00fan lugar a lo largo del camino, todas estas personas dan un paso al frente con una mirada de pura determinaci\u00f3n, decidida, comprometida: y hacen el salto.<\/p>\n<p>Este es el \u201crugido\u201d; este es el momento de la fuerza de voluntad \u2014y es un momento de autodominio en su verdadero sentido. Todo dentro de ellos esta posiblemente gritando a que renuncien, a que sean sensatos, a que jueguen seguros, y a\u00fan as\u00ed son capaces de dominar estos procesos de pensamiento, poni\u00e9ndolos a un lado y eligiendo completar la acci\u00f3n. Controlan sus cuerpos en este punto, y no sus miedos o cualquier otra parte del \u201cmono loco\u201d que es la mente. Es genial ver a alguien alcanzar ese estado, y es incluso mejor sentirlo por ti mismo.<\/p>\n<p>Cuando esto ocurre, es una batalla ganada. La guerra contin\u00faa, sin embargo. Esta es una guerra que nunca termina, despu\u00e9s de todo. El enemigo es incansable, incesante y despiadado. Estar\u00e1 esperando en el campo de batalla cada vez que decidamos ponernos en marcha, con los brazos cruzados y con una sonrisa de complicidad. Nos ha visto antes, nos conoce \u00edntimamente \u2014tal vez mejor que ning\u00fan otro nos ha conocido en la vida\u2014 y sabe perfectamente como quebrarnos. En cambio, aunque, sabemos que es mejor as\u00ed, y entendemos perfectamente el desaf\u00edo, que se presentar\u00e1 cada vez que respondamos a la llamada a las armas.<\/p>\n<p>Es en igualdad de condiciones: simplemente tenemos que dejarnos la piel.<\/p>\n<p><span style=\"color: #c0c0c0;\">\u00a0&#8211;<\/span><br \/>\n<span style=\"color: #c0c0c0;\">Art\u00edculo escrito por Dan Edwardes y cedido a www.umparkour.com<\/span><\/p>\n<p><span style=\"color: #c0c0c0;\">Traducci\u00f3n de Dani Sampayo y Carlos Javier Ferrero, revisi\u00f3n de Adrian Minton.<\/span><\/p>\n<p><span style=\"color: #c0c0c0;\">Puedes leer el art\u00edculo original en ingl\u00e9s en este enlace: <a href=\"http:\/\/danedwardes.com\/2013\/06\/15\/the-war\/\" target=\"_blank\"><span style=\"color: #c0c0c0;\"><strong>The War: Training, Willpower and the Eternal\u00a0Opponent<\/strong><\/span><\/a><\/span><\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"La%20Guerra%3A%20Entrenamiento%2C%20Fuerza%20de%20Voluntad%20y%20el%20Eterno%20Oponente\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>No est\u00e1 de moda en estos d\u00edas el hablar del entrenamiento o la auto-mejora en t\u00e9rminos de conflicto \u2013 a menudo escuchamos que se supone que hay que entrenar inteligente, no duro; a nuestro ritmo; para trabajar dentro de nuestros l\u00edmites; para adherirnos a los principios de la ciencia deportiva de cabo a rabo. Y, [&hellip;]<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"La%20Guerra%3A%20Entrenamiento%2C%20Fuerza%20de%20Voluntad%20y%20el%20Eterno%20Oponente\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":1085,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[29,54,16,334,30,333,335,11,332],"class_list":["post-1083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-general","tag-articulos-2","tag-dan-edwardes","tag-entrenamiento","tag-fuerza-de-voluntad","tag-general-2","tag-la-guerra","tag-oponente","tag-parkour-2","tag-the-war"],"_links":{"self":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/comments?post=1083"}],"version-history":[{"count":2,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1083\/revisions"}],"predecessor-version":[{"id":1087,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1083\/revisions\/1087"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media\/1085"}],"wp:attachment":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media?parent=1083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/categories?post=1083"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/tags?post=1083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}