{"id":1046,"date":"2014-03-28T17:03:27","date_gmt":"2014-03-28T16:03:27","guid":{"rendered":"http:\/\/umparkour.com\/web\/?p=1046"},"modified":"2014-03-28T19:49:47","modified_gmt":"2014-03-28T18:49:47","slug":"reflexiones","status":"publish","type":"post","link":"http:\/\/umparkour.com\/web\/reflexiones\/","title":{"rendered":"#Reflexiones"},"content":{"rendered":"<p><strong>Recopilaci\u00f3n de reflexiones publicadas en la <a href=\"http:\/\/www.facebook.com\/umparkourcom\" target=\"_blank\">p\u00e1gina en facebook de la web<\/a> sobre distintos aspectos del entrenamiento.<\/strong><\/p>\n<p>\u00bfPiensas en lo que entrenas o simplemente entrenas?<\/p>\n<p>Si no tienes un objetivo, si no sigues unos pasos para llegar a \u00e9l puede que alg\u00fan d\u00eda llegues. Sin saber ni c\u00f3mo ni cu\u00e1ndo, pero a\u00fan as\u00ed es probable que puedas llegar. Sin embargo el pensar hacia d\u00f3nde quieres llegar con tu entrenamiento y trazar un plan, por sencillo que sea, pueda ayudarte a alcanzar tus objetivos de manera \u00f3ptima. Piensa en lo que quieres mejorar, en c\u00f3mo quieres mejorarlo, hasta d\u00f3nde quieres llegar con esa mejora, y entonces hazlo. Sigue los pasos, desvi\u00e1ndote de vez en cuando o no, y alcanza esa meta temporal que te lleve a otra a\u00fan m\u00e1s lejana.<\/p>\n<p>Si quieres resultados, primero debes pensar cu\u00e1les son esos resultados y luego planear c\u00f3mo llegar a ellos. No desees simplemente conseguir algo, trabaja para alcanzarlo.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Muchas de las veces, casi la mayor\u00eda dir\u00eda, que escucho a alguien hablar sobre \u00abser fuerte para ser \u00fatil\u00bb hacen referencia a aspectos vitales, a socorrer a terceros en situaciones de emergencia, a estar preparados por si alguna vez tuviesen que ayudar, a construir un cuerpo fuerte y una mente dispuesta a auxiliar y actuar en el momento necesario. Y eso est\u00e1 muy bien, de hecho, est\u00e1 genial. Pero si el entrenamiento forma parte de nuestra vida, \u00bfpor qu\u00e9 no comenzar aplicando ese principio directamente en \u00e9l antes de inventar historias de superh\u00e9roes? <\/span><\/p>\n<p><span style=\"color: #000000;\"> Ayudar al compa\u00f1ero, compartir los entrenamientos y conocimientos, motivar, empujar, alentar al que necesite ese plus durante sus entrenos es una labor important\u00edsima. El que con nuestra actitud podamos motivar a que alguien sea capaz de dar ese pasito m\u00e1s que le haga ser un poco m\u00e1s fuerte o simplemente mejorar en cualquier aspecto su entrenamiento, deber\u00eda ser algo b\u00e1sico y fundamental en una disciplina que si bien es de pr\u00e1ctica individual (al final, saltamos solos), tiene un componente de interacci\u00f3n colectiva y social que responde fielmente a los valores humanos que intentamos no s\u00f3lo cultivar, sino tambi\u00e9n transmitir.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>\u00bfTienes prisa? \u00bfPor qu\u00e9? \u00bfPara qu\u00e9?<\/p>\n<p>Calma, esto lleva tiempo. Debes fortalecer, aprender, pensar\u2026 y nada es inmediato. Ah, \u00bfQue lo que quieres hacer es ese salto tan grande, arriesgado y guay que has visto hacer a otros? \u00bfPor qu\u00e9? \u00bfPara qu\u00e9? Esto va de ti, tu cuerpo y mente, tu capacidad y tu entrenamiento. Si no est\u00e1s preparado, prep\u00e1rate.<\/p>\n<p>Pero con calma, que ni es una carrera al sprint ni una competici\u00f3n. Y ese salto tan grande que quieres hacer seguir\u00e1 ah\u00ed por m\u00e1s tiempo. Y si no, alg\u00fan otro encontrar\u00e1s que te exigir\u00e1 seguir prepar\u00e1ndote.<\/p>\n<p>Porque no hay prisa, porque no hay atajos. Porque eres t\u00fa con toda tu vida \u00fatil por delante.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Entrena sin expectativas superficiales.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Entrena para completarte, para mejorar t\u00fa, no para ser mejor que otro. Entrena porque te llene, no para llenar el armario de ropa de patrocinadores, ni comentarios de aduladores, ni aplausos por tu \u00faltimo gran salto. Que sea el parkour que hagas el que te llene, no el reconocimiento popular. No hay m\u00e1s recompensa que la del buen entrenamiento, no busques ni esperes premios m\u00e1s all\u00e1 de lo que recibas en tu d\u00eda a d\u00eda como consecuencia de tu esfuerzo.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>Todo cuenta.<\/p>\n<p>Ese momento en el que en vez de quedarte sentado por cansancio te levantas y entrenas algo de equilibrio. Cuando tienes las piernas cargadas o alguna peque\u00f1a lesi\u00f3n y decides potenciar el entrenamiento de tu tren superior, o al rev\u00e9s. Esos d\u00edas que los dedicas completamente a estirar, o a pensar en tu entrenamiento, en c\u00f3mo mejorarlo&#8230; Esos d\u00edas en los que no tienes tiempo pero sacas un rato para entrenar f\u00edsico en casa, o salir a correr unos cuantos km al menos&#8230; Al final, todo cuenta. Todo suma y ayuda a coger buenos h\u00e1bitos, constancia, aprovechar cada momento&#8230; Todo cuenta m\u00e1s que el no hacer nada.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">\u00bfQuieres aprovechar mejor tu tiempo de entrenamiento?<\/span><\/p>\n<p><span style=\"color: #000000;\"> No camines, corre. Nos acostumbrado a caminar, a ir tranquilamente de zona en zona rompiendo as\u00ed el ritmo de entrenamiento. \u00bfPor qu\u00e9 no correr? \u00bfPor qu\u00e9 no trazar? Creo que sobra decir lo beneficioso de ese cambio en el desplazamiento habitual y parsimonioso entre los lugares de entrenamiento.<\/span><\/p>\n<p><span style=\"color: #000000;\"> No deseches lo f\u00e1cil. \u00bfCu\u00e1ntas veces alguien ha dejado de hacer alg\u00fan salto, movimiento o reto por pensar que era tan f\u00e1cil que no merec\u00eda la pena? Si es tan f\u00e1cil, \u00bfpor qu\u00e9 no hacerlo? \u00bfAcaso existe miedo de fallar lo \u201cf\u00e1cil\u201d? Vamos, \u00a1hazlo! Pru\u00e9bate que es tan f\u00e1cil y que puedes hacerlo perfecto el 100% de las veces que te lo propongas.<\/span><\/p>\n<p><span style=\"color: #000000;\"> \u00bfSales a la calle solo, calientas y no sabes qu\u00e9 entrenar? Piensa antes de salir, preg\u00fantate qu\u00e9 quieres hacer, qu\u00e9 debes mejorar, qu\u00e9 te apetece hacer ese d\u00eda, si quieres retarte a algo, si tienes alg\u00fan objetivo por cumplir\u2026 No es obligatorio una estructura cerrada del entrenamiento, pero es m\u00e1s que recomendable saber el porqu\u00e9 y el para qu\u00e9 se baja a entrenar.<\/span><\/p>\n<p><span style=\"color: #000000;\"> Si est\u00e1s haciendo repeticiones de alg\u00fan ejercicio para trabajar t\u00e9cnico y\/o f\u00edsico y a\u00fan puedes hacer una m\u00e1s, \u00a1hazla! <\/span><\/p>\n<p><span style=\"color: #000000;\"> Divi\u00e9rtete, socializa, pero entrena. \u00bfCu\u00e1ntas veces has bajado con alguien o en grupo a entrenar y uno contagiaba a otro las pocas ganas de hacer algo? Invierte la situaci\u00f3n, s\u00e9 qui\u00e9n contagie a los dem\u00e1s a activarse y motivarse en el entrenamiento.<\/span><\/p>\n<p><span style=\"color: #000000;\"> \u00bfTerminas de entrenar y te quedas sentado charlando con los dem\u00e1s? Aprovecha para estirar, puedes seguir con la conversaci\u00f3n aprovechando ese tiempo y convirti\u00e9ndolo en otra parte \u00fatil del entrenamiento.<\/span><\/p>\n<p><span style=\"color: #000000;\"> &#8211;<\/span><br \/>\n<span style=\"color: #000000;\"> Esto no son m\u00e1s que una serie de consejos compatibles con muchos otros en los que pensar si te ves reflejado en alguno de sus puntos. Aprovecha cada segundo de tu entrenamiento, haz que todo el tiempo que pasas entrenando cuente para formarte mejor.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>Antes de buscar alargar tus saltos, asegura y controla tu distancia actual. Si quieres evitar ca\u00eddas o golpes innecesarios, la seguridad y control en lo que vayas a hacer debe primar sobre la distancia que quieras conseguir.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">El <span style=\"color: #000000;\">parkour<\/span> no trata de hacer una \u00fanica vez un salto, trata de prepararte para poder hacer cualquier salto en cualquier momento y las veces que sean necesarias. De poder usar tu capacidad para siempre poder avanzar en la direcci\u00f3n que hayas elegido.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>Siempre ser\u00e1 mucho m\u00e1s importante vuestro esp\u00edritu y actitud durante el entrenamiento que la distancia de vuestros saltos.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Muchas veces se escucha a personas quejarse de que en su ciudad hay muchos o pocos, mejores o peores sitios. Sin embargo, al decirlo, no reparan en que casi siempre los lugares para entrenar dependen en gran medida del traceur que vaya a explorarlo para ser mejores o peores. La adaptaci\u00f3n es la clave, reconocer que juego te dar\u00e1 esa localizaci\u00f3n concreta, que posibilidades te dar\u00e1 tu habilidad para explotar la zona y usar tu visi\u00f3n del espacio para convertirlo en una aut\u00e9ntica zona de entrenamiento. <\/span><\/p>\n<p><span style=\"color: #000000;\"> Eso tambi\u00e9n es un aspecto a tener en cuenta y a trabajar, el sacar partido a cada zona en vez de darle la espalda porque a priori no hay nada que hacer.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>Constancia, disciplina, cabeza, actitud, determinaci\u00f3n y pasi\u00f3n. No existe ning\u00fan otro secreto para avanzar en tu <a href=\"https:\/\/www.facebook.com\/hashtag\/parkour\">#parkour<\/a>, s\u00f3lo el buen entrenamiento. Y eso depende \u00fanicamente de ti.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Si algo no te sale, si te cuesta hacerlo bien, si te supone un esfuerzo extra al habitual&#8230; No le des la espalda. Afr\u00f3ntalo, enti\u00e9ndelo y da el paso al frente para superarlo. Hay ejercicios que de forma natural a cada uno le salen m\u00e1s f\u00e1cil que otros, pero la diferencia est\u00e1 entre quienes se esfuerzan en conseguir lo que m\u00e1s trabajo les exige adem\u00e1s de potenciar su habilidad natural, y entre los que se conforman simplemente con lo que les sale f\u00e1cil y a la primera.<\/span><\/p>\n<p><span style=\"color: #000000;\"> El trabajo es necesario en cada \u00e1rea, esforzarse en cada paso y no poner excusas. El objetivo es siempre avanzar.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>No siempre es lo mismo lo que puedes saltar que lo que sabes saltar. Entrena la t\u00e9cnica, controla tu potencia. C\u00f3nocete y aprende a explotar y gestionar tus capacidades. Dale m\u00e1s importancia a hacerlo bien que a simplemente hacerlo.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Recuerda entrenar con tu lado \u00abmalo\u00bb. La capacidad bilateral es fundamental en el manejo del propio cuerpo, saltar con las dos piernas, saber ejecutar cada movimiento indistintamente de lado que lo ataquemos&#8230; Completa tu entrenamiento dedic\u00e1ndole tiempo a entrenar esos detalles, aprende a manejar tu cuerpo al completo. No te estanques en que tienes un lado bueno y otro malo, consigue que en la mayor medida de lo posibe, no haya ni malo ni bueno. Entrena y explota tu capacidad bilateral.-<\/span><\/p>\n<hr size=\"1\" \/>\n<p>Sin aplausos, sin reconocimiento, sin \u00e1nimos, sin c\u00e1maras, sin grupos, sin patrocinadores. Solos t\u00fa y tu determinaci\u00f3n. T\u00fa y tu entrenamiento. T\u00fa y tu esfuerzo. T\u00fa y tu pasi\u00f3n.<\/p>\n<p>Entrena para ti. Ni esto es el circo, ni hay red de seguridad para las pruebas. No hay nadie a quien impresionar.-<\/p>\n<hr size=\"1\" \/>\n<p><span style=\"color: #000000;\">Recordad que con vuestro entrenamiento no ten\u00e9is nada que demostrar a nadie salvo a vosotros mismos. No sint\u00e1is la presi\u00f3n del que mira, del que os acaba de conocer y espera vuestro gran salto, de los aplausos o abrazos, del \u00e9xito o el fracaso. A veces es m\u00e1s dif\u00edcil decir que no se est\u00e1 preparado y dar un paso atr\u00e1s que saltar para satisfacer a los dem\u00e1s. Esto es Parkour, no exhibici\u00f3n o competici\u00f3n. Lo que te juegas en cada salto si fallas, la salud y el f\u00edsico, es m\u00e1s importante que el \u00e9xito y aprobaci\u00f3n ante miradas y aplausos ajenos.-<\/span><\/p>\n<p><span style=\"color: #c0c0c0;\">&#8211;<\/span><\/p>\n<p><span style=\"color: #c0c0c0;\"><span style=\"color: #3366ff;\"><a href=\"http:\/\/www.facebook.com\/umparkourcom\"><span style=\"color: #3366ff;\">www.umparkour.com\/facebook<\/span><\/a><\/span><br \/>\nDani Sampayo. <\/span><\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"%23Reflexiones\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"excerpt":{"rendered":"<p>Recopilaci\u00f3n de reflexiones publicadas en la p\u00e1gina en facebook de la web sobre distintos aspectos del entrenamiento. \u00bfPiensas en lo que entrenas o simplemente entrenas? Si no tienes un objetivo, si no sigues unos pasos para llegar a \u00e9l puede que alg\u00fan d\u00eda llegues. Sin saber ni c\u00f3mo ni cu\u00e1ndo, pero a\u00fan as\u00ed es probable [&hellip;]<\/p>\n<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_toolbar\" href=\"https:\/\/www.hupso.com\/share\/\"><img src=\"http:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top: 5px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_t=new Array(\"Twitter\",\"Facebook\",\"Google Plus\");var hupso_background_t=\"#EAF4FF\";var hupso_border_t=\"#66CCFF\";var hupso_toolbar_size_t=\"small\";var hupso_image_folder_url = \"\";var hupso_twitter_via=\"umparkour\";var hupso_url_t=\"\";var hupso_title_t=\"%23Reflexiones\";<\/script><script type=\"text\/javascript\" src=\"http:\/\/static.hupso.com\/share\/js\/share_toolbar.js\"><\/script><!-- Hupso Share Buttons --><\/div>","protected":false},"author":1,"featured_media":1047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[269,16,244,324],"class_list":["post-1046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-general","tag-consejos","tag-entrenamiento","tag-facebook","tag-reflexiones"],"_links":{"self":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":5,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"predecessor-version":[{"id":1054,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/posts\/1046\/revisions\/1054"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media\/1047"}],"wp:attachment":[{"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/umparkour.com\/web\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}